{"id":119,"date":"2022-02-15T11:37:10","date_gmt":"2022-02-15T11:37:10","guid":{"rendered":"https:\/\/architekturwochebasel.ch\/2022\/?page_id=119"},"modified":"2022-05-19T09:30:42","modified_gmt":"2022-05-19T07:30:42","slug":"programm","status":"publish","type":"page","link":"https:\/\/architekturwochebasel.ch\/2022\/programm\/","title":{"rendered":"Programm"},"content":{"rendered":"<p>asdasd<\/p>\n","protected":false},"excerpt":{"rendered":"<p>asdasd<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":14,"comment_status":"closed","ping_status":"closed","template":"views\/page-programm.blade.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-119","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Programm - Architekturwoche Basel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/architekturwochebasel.ch\/2022\/programm\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Programm - Architekturwoche Basel\" \/>\n<meta property=\"og:description\" content=\"asdasd\" \/>\n<meta property=\"og:url\" content=\"https:\/\/architekturwochebasel.ch\/2022\/programm\/\" \/>\n<meta property=\"og:site_name\" content=\"Architekturwoche Basel\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-19T07:30:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/architekturwochebasel.ch\/2022\/programm\/\",\"url\":\"https:\/\/architekturwochebasel.ch\/2022\/programm\/\",\"name\":\"Programm - Architekturwoche Basel\",\"isPartOf\":{\"@id\":\"https:\/\/architekturwochebasel.ch\/2022\/#website\"},\"datePublished\":\"2022-02-15T11:37:10+00:00\",\"dateModified\":\"2022-05-19T07:30:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/architekturwochebasel.ch\/2022\/programm\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/architekturwochebasel.ch\/2022\/programm\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/architekturwochebasel.ch\/2022\/programm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/architekturwochebasel.ch\/2022\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/architekturwochebasel.ch\/2022\/#website\",\"url\":\"https:\/\/architekturwochebasel.ch\/2022\/\",\"name\":\"Architekturwoche Basel\",\"description\":\"Die neue biennale Plattform f\u00fcr Architektur und Stadtentwicklung\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/architekturwochebasel.ch\/2022\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-CH\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programm - Architekturwoche Basel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/architekturwochebasel.ch\/2022\/programm\/","og_locale":"de_DE","og_type":"article","og_title":"Programm - Architekturwoche Basel","og_description":"asdasd","og_url":"https:\/\/architekturwochebasel.ch\/2022\/programm\/","og_site_name":"Architekturwoche Basel","article_modified_time":"2022-05-19T07:30:42+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/architekturwochebasel.ch\/2022\/programm\/","url":"https:\/\/architekturwochebasel.ch\/2022\/programm\/","name":"Programm - Architekturwoche Basel","isPartOf":{"@id":"https:\/\/architekturwochebasel.ch\/2022\/#website"},"datePublished":"2022-02-15T11:37:10+00:00","dateModified":"2022-05-19T07:30:42+00:00","breadcrumb":{"@id":"https:\/\/architekturwochebasel.ch\/2022\/programm\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/architekturwochebasel.ch\/2022\/programm\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/architekturwochebasel.ch\/2022\/programm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/architekturwochebasel.ch\/2022\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Programm"}]},{"@type":"WebSite","@id":"https:\/\/architekturwochebasel.ch\/2022\/#website","url":"https:\/\/architekturwochebasel.ch\/2022\/","name":"Architekturwoche Basel","description":"Die neue biennale Plattform f\u00fcr Architektur und Stadtentwicklung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/architekturwochebasel.ch\/2022\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-CH"}]}},"_links":{"self":[{"href":"https:\/\/architekturwochebasel.ch\/2022\/wp-json\/wp\/v2\/pages\/119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/architekturwochebasel.ch\/2022\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/architekturwochebasel.ch\/2022\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/architekturwochebasel.ch\/2022\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/architekturwochebasel.ch\/2022\/wp-json\/wp\/v2\/comments?post=119"}],"version-history":[{"count":3,"href":"https:\/\/architekturwochebasel.ch\/2022\/wp-json\/wp\/v2\/pages\/119\/revisions"}],"predecessor-version":[{"id":3732,"href":"https:\/\/architekturwochebasel.ch\/2022\/wp-json\/wp\/v2\/pages\/119\/revisions\/3732"}],"wp:attachment":[{"href":"https:\/\/architekturwochebasel.ch\/2022\/wp-json\/wp\/v2\/media?parent=119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}